{"id":5577,"count":3,"description":"\u041b\u0438\u0446\u0435\u043d\u0437\u0438\u044f \u0432 \u043e\u043d\u043b\u0430\u0439\u043d \u043a\u0430\u0437\u0438\u043d\u043e \u2013 \u0441\u0438\u0435 \u0442\u043e\u0442 \u0432\u043e\u043f\u0440\u043e\u0441, \u043a\u043e\u0442\u043e\u0440\u044b\u0439 \u043f\u043e\u0441\u0442\u043e\u044f\u043d\u043d\u043e \u0431\u0443\u0434\u0443\u0442 \u043e\u0431\u0441\u0443\u0436\u0434\u0430\u0442\u044c. -","link":"https:\/\/poletniteden.com\/index.php\/category\/1win-onlain-408\/","name":"1win Onlain 408","slug":"1win-onlain-408","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/poletniteden.com\/index.php\/wp-json\/wp\/v2\/categories\/5577"}],"collection":[{"href":"https:\/\/poletniteden.com\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/poletniteden.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/poletniteden.com\/index.php\/wp-json\/wp\/v2\/posts?categories=5577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}